{"id":2247,"date":"2020-06-14T17:52:54","date_gmt":"2020-06-14T14:52:54","guid":{"rendered":"https:\/\/wolfisp.com\/?page_id=2247"},"modified":"2023-10-11T14:57:15","modified_gmt":"2023-10-11T11:57:15","slug":"sharedhosting","status":"publish","type":"page","link":"https:\/\/wolfisp.com\/en\/sharedhosting\/","title":{"rendered":"Hosting"},"content":{"rendered":"<p>[vc_row][vc_column]<div id=\"sc_title_1610727287\"\n\t\tclass=\"sc_title color_style_default sc_title_default\"><h1 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\">Shared hosting tariffs<\/h1><div class=\"sc_item_descr sc_title_descr sc_align_center\"><p>Below you can familiarize yourself with hosting tariffs, their characteristics, complete an order, as well as see our advantages.<\/p>\n<\/div><\/div><!-- \/.sc_title -->[vc_empty_space alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221; css=&#8221;.vc_custom_1497512700278{margin-bottom: 0.2rem !important;}&#8221;][vc_tta_tabs color=&#8221;blue&#8221; active_section=&#8221;1&#8243; no_fill_content_area=&#8221;true&#8221;][vc_tta_section title=&#8221;Netherlands&#8221; tab_id=&#8221;nl&#8221;][vc_empty_space alter_height=&#8221;medium&#8221; hide_on_mobile=&#8221;&#8221; css=&#8221;.vc_custom_1497512826085{margin-bottom: 1rem !important;}&#8221;]<div  id=\"sc_price_880584122\"\tclass=\"sc_price color_style_default sc_price_default\"><div class=\"sc_price_columns_wrap sc_item_columns trx_addons_columns_wrap columns_padding_bottom\"><div class=\"trx_addons_column-1_4\"><div class=\"sc_price_item sc_price_item_default\">\n\t\t\t<div class=\"sc_price_item_info\"><h3 class=\"sc_price_item_title\"><span>NL Alpha<\/span><\/h3><div class=\"sc_price_item_price\"><span class=\"sc_price_item_price_before\">$<\/span><span class=\"sc_price_item_price_value\">3<\/span><span class=\"sc_price_item_price_after\">\/mo.<\/span><\/div><div class=\"sc_price_item_details\"><div><span><b>Space:<\/b><\/span><span>5 Gb<\/span><\/div><hr>\n<div><span><b>Sites:<\/b><\/span><span>5<\/span><\/div><hr>\n<div><span><b>Memory PHP:<\/b><\/span><span>512 Mb<\/span><\/div><hr>\n<div><span><b>Traffic: <\/b><\/span><span style=\"font-size: 1.5em;\"><span class=\"unlim-infinite\"> <\/span><\/span><\/div><hr>\n<div><span><b>SSL:<\/b><\/span><span>free<\/span><\/div><\/div><a href=\"https:\/\/my.wolfisp.com\/billmgr?func=register&#038;redirect=startpage%3Dvhost%26startform%3Dvhost%252Eorder%26pricelist%3D1009%26project%3D1\" class=\"sc_price_item_link\">Order<\/a><\/div><!-- \/.sc_price_item_info --><\/div><\/div><div class=\"trx_addons_column-1_4\"><div class=\"sc_price_item sc_price_item_default\">\n\t\t\t<div class=\"sc_price_item_label\">Hot Sale<\/div><div class=\"sc_price_item_info\"><h3 class=\"sc_price_item_title\"><span>NL Beta<\/span><\/h3><div class=\"sc_price_item_price\"><span class=\"sc_price_item_price_before\">$<\/span><span class=\"sc_price_item_price_value\">7<\/span><span class=\"sc_price_item_price_after\">\/mo.<\/span><\/div><div class=\"sc_price_item_details\"><div><span><b>Space:<\/b><\/span><span>10 Gb<\/span><\/div><hr>\n<div><span><b>Sites:<\/b><\/span><span>10<\/span><\/div><hr>\n<div><span><b>Memory PHP:<\/b><\/span><span>1024 Mb<\/span><\/div><hr>\n<div><span><b>Traffic: <\/b><\/span><span style=\"font-size: 1.5em;\"><span class=\"unlim-infinite\"> <\/span><\/span><\/div><hr>\n<div><span><b>SSL:<\/b><\/span><span>free<\/span><\/div><\/div><a href=\"https:\/\/my.wolfisp.com\/billmgr?func=register&#038;redirect=startpage%3Dvhost%26startform%3Dvhost%252Eorder%26pricelist%3D1013%26project%3D1\" class=\"sc_price_item_link\">Order<\/a><\/div><!-- \/.sc_price_item_info --><\/div><\/div><div class=\"trx_addons_column-1_4\"><div class=\"sc_price_item sc_price_item_default\">\n\t\t\t<div class=\"sc_price_item_info\"><h3 class=\"sc_price_item_title\"><span>NL Gamma<\/span><\/h3><div class=\"sc_price_item_price\"><span class=\"sc_price_item_price_before\">$<\/span><span class=\"sc_price_item_price_value\">12<\/span><span class=\"sc_price_item_price_after\">\/mo.<\/span><\/div><div class=\"sc_price_item_details\"><div><span><b>Space:<\/b><\/span><span>15 Gb<\/span><\/div><hr>\n<div><span><b>Sites:<\/b><\/span><span>15<\/span><\/div><hr>\n<div><span><b>Memory PHP:<\/b><\/span><span>1536 Mb<\/span><\/div><hr>\n<div><span><b>Traffic: <\/b><\/span><span style=\"font-size: 1.5em;\"><span class=\"unlim-infinite\"> <\/span><\/span><\/div><hr>\n<div><span><b>SSL:<\/b><\/span><span>free<\/span><\/div><\/div><a href=\"https:\/\/my.wolfisp.com\/billmgr?func=register&#038;redirect=startpage%3Dvhost%26startform%3Dvhost%252Eorder%26pricelist%3D1014%26project%3D1\" class=\"sc_price_item_link\">Order<\/a><\/div><!-- \/.sc_price_item_info --><\/div><\/div><div class=\"trx_addons_column-1_4\"><div class=\"sc_price_item sc_price_item_default\">\n\t\t\t<div class=\"sc_price_item_info\"><h3 class=\"sc_price_item_title\"><span>NL Delta<\/span><\/h3><div class=\"sc_price_item_price\"><span class=\"sc_price_item_price_before\">$<\/span><span class=\"sc_price_item_price_value\">18<\/span><span class=\"sc_price_item_price_after\">\/mo.<\/span><\/div><div class=\"sc_price_item_details\"><div><span><b>Space:<\/b><\/span><span>20 Gb<\/span><\/div><hr>\n<div><span><b>Sites:<\/b><\/span><span>20<\/span><\/div><hr>\n<div><span><b>Memory PHP:<\/b><\/span><span>2048 Mb<\/span><\/div><hr>\n<div><span><b>Traffic: <\/b><\/span><span style=\"font-size: 1.5em;\"><span class=\"unlim-infinite\"> <\/span><\/span><\/div><hr>\n<div><span><b>SSL:<\/b><\/span><span>free<\/span><\/div><\/div><a href=\"https:\/\/my.wolfisp.com\/billmgr?func=register&#038;redirect=startpage%3Dvhost%26startform%3Dvhost%252Eorder%26pricelist%3D1015%26project%3D1\" class=\"sc_price_item_link\">Order<\/a><\/div><!-- \/.sc_price_item_info --><\/div><\/div><\/div><\/div><!-- \/.sc_price -->[\/vc_tta_section][\/vc_tta_tabs][vc_empty_space alter_height=&#8221;medium&#8221; hide_on_mobile=&#8221;&#8221; css=&#8221;.vc_custom_1497512826085{margin-bottom: 1rem !important;}&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1544887894252{background-color: #f6f7f9 !important;}&#8221;][vc_column][vc_empty_space alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;]<div id=\"sc_title_806847291\"\n\t\tclass=\"sc_title color_style_default sc_title_default\"><h1 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\">All tariffs include<\/h1><\/div><!-- \/.sc_title -->[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; css=&#8221;.vc_custom_1544894473238{background-color: #f6f7f9 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221; css=&#8221;.vc_custom_1544895465677{margin-bottom: 2.1rem !important;}&#8221;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list left circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:24px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:8px;border-width:1px;border-style:none;background:#ffffff;color:#903de2;border-color:#333333;\"><i class=\"Defaults-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-2517\" style=\"font-size:8px;\"><p class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-2517 p'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Control panel ISPmanager 5 Bussines<\/p><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-2517 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>The convenient control panel for managing hosting.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:24px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:8px;border-width:1px;border-style:none;background:#ffffff;color:#903de2;border-color:#333333;\"><i class=\"Defaults-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7732\" style=\"font-size:8px;\"><p class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-7732 p'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Unlimited traffic<\/p><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7732 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Unlimited traffic for Your sites.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:24px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:8px;border-width:1px;border-style:none;background:#ffffff;color:#903de2;border-color:#333333;\"><i class=\"Defaults-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-9399\" style=\"font-size:8px;\"><p class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-9399 p'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Backup<\/p><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-9399 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>We perform daily data backup.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:24px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:8px;border-width:1px;border-style:none;background:#ffffff;color:#903de2;border-color:#333333;\"><i class=\"Defaults-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5478\" style=\"font-size:8px;\"><p class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-5478 p'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">PHP Selector<\/p><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5478 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>The following PHP versions are available: 7.4, 7.3, 7.2, 7.1, 7.0, 5.6, 5.5, 5.5.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:24px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:8px;border-width:1px;border-style:none;background:#ffffff;color:#903de2;border-color:#333333;\"><i class=\"Defaults-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-1983\" style=\"font-size:8px;\"><p class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-1983 p'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Database servers<\/p><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-1983 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>MariaDB 10, MySQL 5.6.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:24px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:8px;border-width:1px;border-style:none;background:#ffffff;color:#903de2;border-color:#333333;\"><i class=\"Defaults-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7185\" style=\"font-size:8px;\"><p class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-7185 p'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">MySQL Control Panel<\/p><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7185 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>PHPMyAdmin.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221; css=&#8221;.vc_custom_1544895471243{margin-bottom: 2.1rem !important;}&#8221;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list left circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:24px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:8px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-1244\" style=\"font-size:8px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-1244 span'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">HTTP\/2 Support<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-1244 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Even faster with HTTP\/2.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:24px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:8px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-6297\" style=\"font-size:8px;\"><p class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-6297 p'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Free SSL certificates<\/p><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-6297 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>We provide free SSL based on Let&#8217;s Encrypt certificate authority.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:24px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:8px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7584\" style=\"font-size:8px;\"><p class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-7584 p'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Convenient Web interface for mail<\/p><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7584 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>RounCube control panel for working with mail.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:24px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:8px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-2881\" style=\"font-size:8px;\"><p class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-2881 p'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">SSH, sFTP access<\/p><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-2881 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Enabled on request.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:24px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:8px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-8375\" style=\"font-size:8px;\"><p class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-8375 p'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Unlimited number of mailboxes<\/p><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-8375 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>We do not limit the number of mailboxes for your domains.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:24px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:8px;border-width:1px;border-style:none;background:#ffffff;color:#333333;border-color:#333333;\"><i class=\"Defaults-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7787\" style=\"font-size:8px;\"><span class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-7787 span'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Support for scripting languages<\/span><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7787 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Perl, Python.<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space alter_height=&#8221;medium&#8221; hide_on_mobile=&#8221;&#8221; css=&#8221;.vc_custom_1592139989094{margin-bottom: 1rem !important;}&#8221;]<div id=\"sc_title_1750530290\"\n\t\tclass=\"sc_title color_style_default sc_title_default\"><h1 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\">Our advantage<\/h1><\/div><!-- \/.sc_title -->[vc_empty_space alter_height=&#8221;medium&#8221; hide_on_mobile=&#8221;&#8221;][vc_empty_space alter_height=&#8221;large&#8221; hide_on_mobile=&#8221;&#8221; css=&#8221;.vc_custom_1592140080968{margin-top: -5.5rem !important;}&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243; el_class=&#8221;vds_icon_color&#8221;]<div class=\"aio-icon-component    style_2\"><div id=\"Info-box-wrap-8840\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#a126d6;font-size:48px;display:inline-block;\">\n\t<i class=\"icomoon-linux\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-8840 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">OS CloudLinux<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-8840 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Thanks to CloudLinux, all users are isolated from each other.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component --><div class=\"aio-icon-component    style_2\"><div id=\"Info-box-wrap-4771\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#a126d6;font-size:48px;display:inline-block;\">\n\t<i class=\"icomoon-forwarding\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-4771 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Help with migration<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-4771 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">We will gladly assist in the transfer of your sites and services to us.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_2\"><div id=\"Info-box-wrap-5252\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#a126d6;font-size:48px;display:inline-block;\">\n\t<i class=\"icomoon-24hour\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-5252 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Support 24\/7<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-5252 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Our experienced specialists are always happy to help you solve problems.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component --><div class=\"aio-icon-component    style_2\"><div id=\"Info-box-wrap-9357\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#a126d6;font-size:48px;display:inline-block;\">\n\t<i class=\"icomoon-1m-sites\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-9357 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Convenient control panel<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-9357 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">For hosting management, we provide a convenient ISPmanager control panel.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div class=\"aio-icon-component    style_2\"><div id=\"Info-box-wrap-8559\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#a126d6;font-size:48px;display:inline-block;\">\n\t<i class=\"icomoon-untitled-7\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-8559 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Fast SSD drives<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-8559 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">We use SSD drives on all tariffs, which allows us to increase the speed many times.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component --><div class=\"aio-icon-component    style_2\"><div id=\"Info-box-wrap-3107\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#a126d6;font-size:48px;display:inline-block;\">\n\t<i class=\"icomoon-builder\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-3107 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">One click CMS installation<\/h3><\/div> <!-- header --><div class=\"aio-icon-description ult-responsive\"  data-ultimate-target='#Info-box-wrap-3107 .aio-icon-description'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">You can install your favorite CMS with just one click.<\/div> <!-- description --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_empty_space alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221; css=&#8221;.vc_custom_1497512700278{margin-bottom: 0.2rem !important;}&#8221;][vc_tta_tabs color=&#8221;blue&#8221; active_section=&#8221;1&#8243; no_fill_content_area=&#8221;true&#8221;][vc_tta_section title=&#8221;Netherlands&#8221; tab_id=&#8221;nl&#8221;][vc_empty_space alter_height=&#8221;medium&#8221; hide_on_mobile=&#8221;&#8221; css=&#8221;.vc_custom_1497512826085{margin-bottom: 1rem !important;}&#8221;][\/vc_tta_section][\/vc_tta_tabs][vc_empty_space alter_height=&#8221;medium&#8221; hide_on_mobile=&#8221;&#8221; css=&#8221;.vc_custom_1497512826085{margin-bottom: 1rem !important;}&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1544887894252{background-color: #f6f7f9 !important;}&#8221;][vc_column][vc_empty_space alter_height=&#8221;small&#8221; hide_on_mobile=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; css=&#8221;.vc_custom_1544894473238{background-color: #f6f7f9 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/wolfisp.com\/en\/wp-json\/wp\/v2\/pages\/2247"}],"collection":[{"href":"https:\/\/wolfisp.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wolfisp.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wolfisp.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wolfisp.com\/en\/wp-json\/wp\/v2\/comments?post=2247"}],"version-history":[{"count":13,"href":"https:\/\/wolfisp.com\/en\/wp-json\/wp\/v2\/pages\/2247\/revisions"}],"predecessor-version":[{"id":2263,"href":"https:\/\/wolfisp.com\/en\/wp-json\/wp\/v2\/pages\/2247\/revisions\/2263"}],"wp:attachment":[{"href":"https:\/\/wolfisp.com\/en\/wp-json\/wp\/v2\/media?parent=2247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}